{"id":49225,"date":"2021-01-19T22:44:43","date_gmt":"2021-01-19T21:44:43","guid":{"rendered":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg"},"modified":"2021-01-19T22:45:15","modified_gmt":"2021-01-19T21:45:15","slug":"teaser-huttenschule-turnhalle","status":"inherit","type":"attachment","link":"https:\/\/spirit-of-football.de\/en\/teaser-huttenschule-turnhalle\/","title":{"rendered":"Teaser Huttenschule Turnhalle"},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-49225","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"124\" src=\"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-300x124.jpg\" class=\"attachment-medium size-medium\" alt=\"Huttenschule, Ein Ball, Eine Welt, Erfurt\" srcset=\"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-300x124.jpg 300w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-18x7.jpg 18w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-553x228.jpg 553w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-640x264.jpg 640w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-618x255.jpg 618w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-240x99.jpg 240w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-980x404.jpg 980w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-768x317.jpg 768w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-1024x422.jpg 1024w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-500x206.jpg 500w, https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"49225\" data-permalink=\"https:\/\/spirit-of-football.de\/en\/teaser-huttenschule-turnhalle\/\" data-orig-file=\"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg\" data-orig-size=\"1200,495\" data-comments-opened=\"1\" data-image-title=\"Teaser Huttenschule Turnhalle\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-1024x422.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Huttenschule, Ein Ball, Eine Welt, Erfurt","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":495,"file":"2021\/01\/Teaser-Huttenschule-Turnhalle.jpg","filesize":96996,"sizes":{"trp-custom-language-flag":{"file":"Teaser-Huttenschule-Turnhalle-18x7.jpg","width":18,"height":7,"filesize":774,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-18x7.jpg"},"the-ball-v2-listings":{"file":"Teaser-Huttenschule-Turnhalle-553x228.jpg","width":553,"height":228,"filesize":34257,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-553x228.jpg"},"medium-640":{"file":"Teaser-Huttenschule-Turnhalle-640x264.jpg","width":640,"height":264,"filesize":41804,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-640x264.jpg"},"medium-618":{"file":"Teaser-Huttenschule-Turnhalle-618x255.jpg","width":618,"height":255,"filesize":40118,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-618x255.jpg"},"thumbnail-240":{"file":"Teaser-Huttenschule-Turnhalle-240x99.jpg","width":240,"height":99,"filesize":9235,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-240x99.jpg"},"980x980":{"file":"Teaser-Huttenschule-Turnhalle-980x404.jpg","width":980,"height":404,"filesize":77591,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-980x404.jpg"},"pledge-quote":{"file":"Teaser-Huttenschule-Turnhalle-681x495.jpg","width":681,"height":495,"filesize":58548,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-681x495.jpg"},"individual-avatar":{"file":"Teaser-Huttenschule-Turnhalle-640x495.jpg","width":640,"height":495,"filesize":52510,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-640x495.jpg"},"thumbnail":{"file":"Teaser-Huttenschule-Turnhalle-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-80x80.jpg"},"medium":{"file":"Teaser-Huttenschule-Turnhalle-300x124.jpg","width":300,"height":124,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-300x124.jpg"},"medium_large":{"file":"Teaser-Huttenschule-Turnhalle-768x317.jpg","width":768,"height":317,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-768x317.jpg"},"large":{"file":"Teaser-Huttenschule-Turnhalle-1024x422.jpg","width":1024,"height":422,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-1024x422.jpg"},"post-thumbnail":{"file":"Teaser-Huttenschule-Turnhalle-1000x360.jpg","width":1000,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-1000x360.jpg"},"post-image":{"file":"Teaser-Huttenschule-Turnhalle-674x140.jpg","width":674,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-674x140.jpg"},"slider-full":{"file":"Teaser-Huttenschule-Turnhalle-980x360.jpg","width":980,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-980x360.jpg"},"thumbnail-large":{"file":"Teaser-Huttenschule-Turnhalle-600x200.jpg","width":600,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-600x200.jpg"},"thumbnail-post":{"file":"Teaser-Huttenschule-Turnhalle-210x160.jpg","width":210,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-210x160.jpg"},"slider-image":{"file":"Teaser-Huttenschule-Turnhalle-635x344.jpg","width":635,"height":344,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-635x344.jpg"},"large-feature":{"file":"Teaser-Huttenschule-Turnhalle-1000x360.jpg","width":1000,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-1000x360.jpg"},"small-feature":{"file":"Teaser-Huttenschule-Turnhalle-500x206.jpg","width":500,"height":206,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-500x206.jpg"},"Bannerbild":{"file":"Teaser-Huttenschule-Turnhalle-547x231.jpg","width":547,"height":231,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-547x231.jpg"},"Bild im Text":{"file":"Teaser-Huttenschule-Turnhalle-200x130.jpg","width":200,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-200x130.jpg"},"gallerie":{"file":"Teaser-Huttenschule-Turnhalle-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-150x150.jpg"},"bannerbild":{"file":"Teaser-Huttenschule-Turnhalle-640x300.jpg","width":640,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle-640x300.jpg"},"full":{"file":"Teaser-Huttenschule-Turnhalle.jpg","width":1200,"height":495,"mime_type":"image\/jpeg","source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/spirit-of-football.de\/wp-content\/uploads\/sites\/12\/2021\/01\/Teaser-Huttenschule-Turnhalle.jpg","filename":"Teaser-Huttenschule-Turnhalle.jpg","filesize":96996,"_links":{"self":[{"href":"https:\/\/spirit-of-football.de\/en\/wp-json\/wp\/v2\/media\/49225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spirit-of-football.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/spirit-of-football.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/spirit-of-football.de\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/spirit-of-football.de\/en\/wp-json\/wp\/v2\/comments?post=49225"}]}}